{"id":2261,"date":"2023-10-26T09:42:25","date_gmt":"2023-10-26T12:42:25","guid":{"rendered":"https:\/\/quasarhomecenter.com\/?post_type=product&#038;p=2261"},"modified":"2023-11-30T15:51:10","modified_gmt":"2023-11-30T18:51:10","slug":"ventilador-de-mesa","status":"publish","type":"product","link":"https:\/\/quasarhomecenter.com\/index.php\/product\/ventilador-de-mesa\/","title":{"rendered":"Ventilador de mesa"},"content":{"rendered":"\n<h2 class=\"wp-block-heading has-vivid-cyan-blue-color has-text-color\" id=\"block-bd49212d-e09d-4809-b421-60d6fdfd5851\">Caracter\u00edsticas destacadas<\/h2>\n\n\n\n<p>El ventilador de mesa mini y recargable es un dispositivo compacto y port\u00e1til dise\u00f1ado para proporcionar una brisa refrescante en espacios reducidos. Su tama\u00f1o mini lo hace ideal para escritorios, mesas de trabajo o llevarlo consigo donde lo necesite.<\/p>\n\n\n\n<p>Al ser recargable, este ventilador ofrece la conveniencia de no depender de cables durante su uso, lo que lo hace ideal para situaciones en las que no hay acceso cercano a una toma de corriente. Su dise\u00f1o compacto facilita su transporte y colocaci\u00f3n en diferentes \u00e1reas.<\/p>\n\n\n\n<p>Ventilador de mesa<br>Mini, Recargable<br>C\u00f3d: 19166<\/p>\n\n\n\n<ul class=\"wp-block-list\"><\/ul>\n\n\n\n<h3 class=\"wp-block-heading has-vivid-cyan-blue-color has-text-color\" id=\"block-8e8f1f44-0cee-4c2a-b155-50e11e155606\">Caracter\u00edsticas generales<\/h3>\n\n\n\n<figure class=\"wp-block-table\"><table><tbody><tr><td><strong>Marca<\/strong><\/td><td>Ventilador de mesa <\/td><\/tr><tr><td><strong>L\u00ednea<\/strong><\/td><td>Hogar<\/td><\/tr><tr><td><strong>Modelo<\/strong><\/td><td>Mesa<\/td><\/tr><tr><td><strong>Voltaje<\/strong><\/td><td>\ufeff<\/td><\/tr><tr><td><strong>Frecuencia de funcionamiento<\/strong><\/td><td>50\/60Hz<\/td><\/tr><tr><td><strong>Material de las cuchillas<\/strong><\/td><td>Acero inoxidable<\/td><\/tr><\/tbody><\/table><\/figure>\n\n\n\n<h2 class=\"wp-block-heading has-vivid-cyan-blue-color has-text-color\" id=\"block-a77ccdad-4a3d-4f34-9a7b-7a1ff7bed83b\">Dimensiones y peso<\/h2>\n\n\n\n<p id=\"block-12c36865-ed0f-41b3-bdca-d0120eed6400\">Largo:&nbsp;0 cm<\/p>\n\n\n\n<p id=\"block-d2521160-be65-4ed4-a0a9-79c5467c7c3a\">Ancho: 0 cm<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Mini, Recargable<br \/>C\u00f3d: 19166<\/p>\n","protected":false},"featured_media":2996,"comment_status":"open","ping_status":"closed","template":"","meta":{"om_disable_all_campaigns":false,"_uag_custom_page_level_css":"","_monsterinsights_skip_tracking":false},"product_cat":[29],"product_tag":[133],"class_list":{"0":"post-2261","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-electrodomesticos","7":"product_tag-ventilacion","9":"first","10":"instock","11":"shipping-taxable","12":"purchasable","13":"product-type-simple"},"aioseo_notices":[],"jetpack_sharing_enabled":true,"uagb_featured_image_src":{"full":["https:\/\/quasarhomecenter.com\/wp-content\/uploads\/2023\/11\/19166-Banco-de-Datos.png",2295,2295,false],"thumbnail":["https:\/\/quasarhomecenter.com\/wp-content\/uploads\/2023\/11\/19166-Banco-de-Datos-150x150.png",150,150,true],"medium":["https:\/\/quasarhomecenter.com\/wp-content\/uploads\/2023\/11\/19166-Banco-de-Datos-300x300.png",300,300,true],"medium_large":["https:\/\/quasarhomecenter.com\/wp-content\/uploads\/2023\/11\/19166-Banco-de-Datos-768x768.png",768,768,true],"large":["https:\/\/quasarhomecenter.com\/wp-content\/uploads\/2023\/11\/19166-Banco-de-Datos-1024x1024.png",1024,1024,true],"1536x1536":["https:\/\/quasarhomecenter.com\/wp-content\/uploads\/2023\/11\/19166-Banco-de-Datos-1536x1536.png",1536,1536,true],"2048x2048":["https:\/\/quasarhomecenter.com\/wp-content\/uploads\/2023\/11\/19166-Banco-de-Datos-2048x2048.png",2048,2048,true],"mailpoet_newsletter_max":["https:\/\/quasarhomecenter.com\/wp-content\/uploads\/2023\/11\/19166-Banco-de-Datos-1320x1320.png",1320,1320,true],"woocommerce_thumbnail":["https:\/\/quasarhomecenter.com\/wp-content\/uploads\/2023\/11\/19166-Banco-de-Datos-514x514.png",514,514,true],"woocommerce_single":["https:\/\/quasarhomecenter.com\/wp-content\/uploads\/2023\/11\/19166-Banco-de-Datos-500x500.png",500,500,true],"woocommerce_gallery_thumbnail":["https:\/\/quasarhomecenter.com\/wp-content\/uploads\/2023\/11\/19166-Banco-de-Datos-100x100.png",100,100,true]},"uagb_author_info":{"display_name":"quasarhomecenter.com","author_link":"https:\/\/quasarhomecenter.com\/index.php\/author\/"},"uagb_comment_info":0,"uagb_excerpt":"Mini, RecargableC\u00f3d: 19166","_links":{"self":[{"href":"https:\/\/quasarhomecenter.com\/index.php\/wp-json\/wp\/v2\/product\/2261","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quasarhomecenter.com\/index.php\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/quasarhomecenter.com\/index.php\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/quasarhomecenter.com\/index.php\/wp-json\/wp\/v2\/comments?post=2261"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quasarhomecenter.com\/index.php\/wp-json\/wp\/v2\/media\/2996"}],"wp:attachment":[{"href":"https:\/\/quasarhomecenter.com\/index.php\/wp-json\/wp\/v2\/media?parent=2261"}],"wp:term":[{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/quasarhomecenter.com\/index.php\/wp-json\/wp\/v2\/product_cat?post=2261"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/quasarhomecenter.com\/index.php\/wp-json\/wp\/v2\/product_tag?post=2261"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}